{"id":29,"count":22,"description":"<h2>Una <strong>guida di\u00a0Budapest\u00a0<\/strong>con tutte le informazioni utili sulla capitale. Come arrivare, muoversi, cosa visitare, info pratiche e numeri di emergenza.<\/h2>","link":"https:\/\/www.10cose.it\/category\/budapest","name":"Budapest","slug":"budapest","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Budapest | Guida di Budapest | Informazioni su Budapest<\/title>\n<meta name=\"description\" content=\"Una guida di 30 pagine dedicata a Budapest. Monumenti, chiese, piazze, come arrivare, muoversi e tutte le informazioni utili per scoprire Budapest.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.10cose.it\/en\/category\/budapest\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Budapest | Guida di Budapest | Informazioni su Budapest\" \/>\n<meta property=\"og:description\" content=\"Una guida di 30 pagine dedicata a Budapest. Monumenti, chiese, piazze, come arrivare, muoversi e tutte le informazioni utili per scoprire Budapest.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.10cose.it\/category\/budapest\" \/>\n<meta property=\"og:site_name\" content=\"10Cose.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.10cose.it\/category\/budapest\",\"url\":\"https:\/\/www.10cose.it\/category\/budapest\",\"name\":\"Budapest | Guida di Budapest | Informazioni su Budapest\",\"isPartOf\":{\"@id\":\"https:\/\/www.10cose.it\/en#website\"},\"description\":\"Una guida di 30 pagine dedicata a Budapest. Monumenti, chiese, piazze, come arrivare, muoversi e tutte le informazioni utili per scoprire Budapest.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.10cose.it\/category\/budapest#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.10cose.it\/category\/budapest#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.10cose.it\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Budapest\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.10cose.it\/en#website\",\"url\":\"https:\/\/www.10cose.it\/en\",\"name\":\"10Cose.it\",\"description\":\"La guida turistica che conta\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.10cose.it\/en?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Budapest | Guida di Budapest | Informazioni su Budapest","description":"Una guida di 30 pagine dedicata a Budapest. Monumenti, chiese, piazze, come arrivare, muoversi e tutte le informazioni utili per scoprire Budapest.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.10cose.it\/en\/category\/budapest","og_locale":"en_US","og_type":"article","og_title":"Budapest | Guida di Budapest | Informazioni su Budapest","og_description":"Una guida di 30 pagine dedicata a Budapest. Monumenti, chiese, piazze, come arrivare, muoversi e tutte le informazioni utili per scoprire Budapest.","og_url":"https:\/\/www.10cose.it\/category\/budapest","og_site_name":"10Cose.it","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.10cose.it\/category\/budapest","url":"https:\/\/www.10cose.it\/category\/budapest","name":"Budapest | Guida di Budapest | Informazioni su Budapest","isPartOf":{"@id":"https:\/\/www.10cose.it\/en#website"},"description":"Una guida di 30 pagine dedicata a Budapest. Monumenti, chiese, piazze, come arrivare, muoversi e tutte le informazioni utili per scoprire Budapest.","breadcrumb":{"@id":"https:\/\/www.10cose.it\/category\/budapest#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.10cose.it\/category\/budapest#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.10cose.it\/en"},{"@type":"ListItem","position":2,"name":"Budapest"}]},{"@type":"WebSite","@id":"https:\/\/www.10cose.it\/en#website","url":"https:\/\/www.10cose.it\/en","name":"10Cose.it","description":"La guida turistica che conta","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.10cose.it\/en?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.10cose.it\/en\/wp-json\/wp\/v2\/categories\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.10cose.it\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.10cose.it\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.10cose.it\/en\/wp-json\/wp\/v2\/posts?categories=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}